{"id":30738,"date":"2026-05-12T20:44:27","date_gmt":"2026-05-13T02:44:27","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=30738"},"modified":"2026-05-12T20:44:28","modified_gmt":"2026-05-13T02:44:28","slug":"gp-betzabe-martinez-refuerza-estrategia-de-atencion-a-la-salud-mental-en-gomez-palacio","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2026\/05\/12\/gp-betzabe-martinez-refuerza-estrategia-de-atencion-a-la-salud-mental-en-gomez-palacio\/","title":{"rendered":"#GP. Betzab\u00e9 Mart\u00ednez refuerza estrategia de atenci\u00f3n a la salud mental en G\u00f3mez Palacio*"},"content":{"rendered":"\n<p>La presidenta municipal de G\u00f3mez Palacio, Betzab\u00e9 Mart\u00ednez Arango, inform\u00f3 que el Gobierno Municipal trabaja en el fortalecimiento de estrategias de prevenci\u00f3n y atenci\u00f3n en salud mental, especialmente dirigidas a j\u00f3venes y personas en situaci\u00f3n de vulnerabilidad.<\/p>\n\n\n\n<p>La alcaldesa reconoci\u00f3 que los casos de depresi\u00f3n, adicciones y suicidio representan una problem\u00e1tica que debe atenderse de manera integral, mediante la coordinaci\u00f3n entre autoridades, instituciones educativas, especialistas y familias.<\/p>\n\n\n\n<p>\u201cEs un tema que debemos atender y estamos gestionando c\u00f3mo ampliar el acceso a atenci\u00f3n psiqui\u00e1trica cuando sea necesario\u201d, expres\u00f3.<\/p>\n\n\n\n<p>Betzab\u00e9 Mart\u00ednez explic\u00f3 que actualmente el Municipio ha apoyado con traslados a la ciudad de Durango en aquellos casos donde se requiere atenci\u00f3n especializada; sin embargo, subray\u00f3 que la prioridad es fortalecer las acciones preventivas y generar espacios de desarrollo para ni\u00f1as, ni\u00f1os y j\u00f3venes.<\/p>\n\n\n\n<p>En este sentido, destac\u00f3 programas como \u201cBoxeando por la Paz\u201d y \u201cJ\u00f3venes Unen al Barrio\u201d, estrategia impulsada por el Gobierno Federal que ya opera en G\u00f3mez Palacio y que contempla 100 becas para j\u00f3venes de entre 12 y 29 a\u00f1os que actualmente no estudian.<\/p>\n\n\n\n<p>A trav\u00e9s de este programa, las y los beneficiarios reciben un apoyo econ\u00f3mico mensual de 4 mil pesos para continuar sus estudios, integrarse a actividades deportivas, culturales o realizar servicio social.<\/p>\n\n\n\n<p>\u201cBuscamos rescatar a nuestros j\u00f3venes de las adicciones y acercarles oportunidades de desarrollo, identidad y pertenencia\u201d, se\u00f1al\u00f3 la presidenta municipal.<\/p>\n\n\n\n<p>Asimismo, reconoci\u00f3 el trabajo preventivo que realiza el Grupo Violeta, cuyos integrantes han intervenido oportunamente en casos de personas que intentaban atentar contra su vida, principalmente en espacios p\u00fablicos y puentes de la ciudad.<\/p>\n\n\n\n<p>Ante ello, Betzab\u00e9 Mart\u00ednez hizo un llamado a la ciudadan\u00eda para reportar de inmediato cualquier situaci\u00f3n de riesgo y permitir que las corporaciones y grupos de apoyo act\u00faen oportunamente.<\/p>\n\n\n\n<p>\u201cCuando detecten alg\u00fan caso de riesgo, les pedimos que nos llamen de inmediato para acudir junto con Grupo Violeta y brindar apoyo\u201d, manifest\u00f3.<\/p>\n\n\n\n<p>La alcaldesa inform\u00f3 adem\u00e1s que desde la Comisi\u00f3n de Salud del Cabildo se trabaja en propuestas para fortalecer la atenci\u00f3n especializada, entre ellas la creaci\u00f3n de un centro municipal de atenci\u00f3n psicol\u00f3gica y psiqui\u00e1trica.<\/p>\n\n\n\n<p>Por su parte, la directora del DIF G\u00f3mez Palacio, Sanjuana Guadalupe Aguirre, dio a conocer que se mantiene abierta la convocatoria para incorporar psic\u00f3logos y psiquiatras a la plantilla laboral del organismo, con el objetivo de ampliar la atenci\u00f3n a la poblaci\u00f3n en temas relacionados con salud mental, prevenci\u00f3n del suicidio, autolesiones, adicciones y violencia familiar.<\/p>\n\n\n\n<p>Con estas acciones, el Gobierno Municipal reiter\u00f3 su compromiso de impulsar pol\u00edticas p\u00fablicas enfocadas en la prevenci\u00f3n, el bienestar emocional y la reconstrucci\u00f3n del tejido social en G\u00f3mez Palacio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta municipal de G\u00f3mez Palacio, Betzab\u00e9 Mart\u00ednez Arango, inform\u00f3 que el Gobierno Municipal trabaja en el fortalecimiento de estrategias de prevenci\u00f3n y atenci\u00f3n en salud mental, especialmente dirigidas a j\u00f3venes y personas en situaci\u00f3n de vulnerabilidad. La alcaldesa reconoci\u00f3 que los casos de depresi\u00f3n, adicciones y suicidio representan una problem\u00e1tica que debe atenderse de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30740,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/30738"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=30738"}],"version-history":[{"count":1,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/30738\/revisions"}],"predecessor-version":[{"id":30741,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/30738\/revisions\/30741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/30740"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=30738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=30738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=30738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}