{"id":30732,"date":"2026-05-12T20:35:16","date_gmt":"2026-05-13T02:35:16","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=30732"},"modified":"2026-05-12T20:35:16","modified_gmt":"2026-05-13T02:35:16","slug":"congresocoahuila-realizan-pronunciamiento-con-motivo-del-dia-mundial-del-lupus","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2026\/05\/12\/congresocoahuila-realizan-pronunciamiento-con-motivo-del-dia-mundial-del-lupus\/","title":{"rendered":"#CongresoCoahuila. Realizan pronunciamiento con motivo del \u201cD\u00eda Mundial del Lupus\u201d"},"content":{"rendered":"\n<p><strong>Saltillo, Coahuila, 12 de mayo de 2026<\/strong>.- En sesi\u00f3n del Congreso del Estado, la diputada Mar\u00eda del Mar Trevi\u00f1o Garza, realiz\u00f3 un pronunciamiento con motivo del \u201cD\u00eda Mundial del Lupus\u201d que se conmemora en el mes de mayo, expresando respeto, solidaridad y admiraci\u00f3n a quienes viven con este padecimiento que es, en muchos casos, una discapacidad invisible. La diputada explic\u00f3 que vivir con este padecimiento significa aprender a negociar con el propio cuerpo, enfrentar la fatiga que no desaparece con dormir, soportar el dolor en las articulaciones que no ceden, tener reca\u00eddas inesperadas, llevar a cabo tratamientos que exigen constancia y paciencia, y la incertidumbre permanente sobre lo que vendr\u00e1. Y todo ello, muchas veces, en silencio. El lupus es, en muchos casos, una discapacidad invisible. Quienes lo padecen a menudo tienen una apariencia saludable que no corresponde a lo que viven en su interior. Esa invisibilidad genera incomprensi\u00f3n: en el sal\u00f3n de clases, cuando \u00e9l o la estudiante no puede concentrarse o faltan con frecuencia; en el centro de trabajo, cuando se requiere una adaptaci\u00f3n razonable y no se otorga porque \u201cno se nota\u201d; en el n\u00facleo familiar, donde a veces se interpreta como falta de \u00e1nimo lo que en realidad es una respuesta inmunol\u00f3gica fuera de control. \u201cDesde esta legislatura, hacemos de nueva cuenta un llamado a las autoridades de salud, educaci\u00f3n y del trabajo para que las pol\u00edticas p\u00fablicas contemplen las necesidades espec\u00edficas de quienes viven con enfermedades autoinmunes cr\u00f3nicas. Que los protocolos de atenci\u00f3n sean sensibles, que las aulas y centros de trabajo sean espacios de inclusi\u00f3n, y que el sistema nunca les obligue a demostrar su dolor para recibir un trato digno\u201d expres\u00f3 la diputada Asimismo, mencion\u00f3 la responsabilidad como diputados de legislar y gestionar para que el apoyo sea permanente. Reconoci\u00f3 tambi\u00e9n a los familiares de quienes padecen esta enfermedad, m\u00e9dicos, cuidadores y a las asociaciones que traducen el dolor en propuestas y en comunidad: \u201cA todos ellos, les reiteramos que en este Congreso se les escucha y se les reconoce\u201d, se\u00f1al\u00f3 Mar\u00eda del Mar Trevi\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila, 12 de mayo de 2026.- En sesi\u00f3n del Congreso del Estado, la diputada Mar\u00eda del Mar Trevi\u00f1o Garza, realiz\u00f3 un pronunciamiento con motivo del \u201cD\u00eda Mundial del Lupus\u201d que se conmemora en el mes de mayo, expresando respeto, solidaridad y admiraci\u00f3n a quienes viven con este padecimiento que es, en muchos casos, una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30733,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/30732"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=30732"}],"version-history":[{"count":1,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/30732\/revisions"}],"predecessor-version":[{"id":30734,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/30732\/revisions\/30734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/30733"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=30732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=30732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=30732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}