{"id":2009,"date":"2024-02-20T19:32:35","date_gmt":"2024-02-21T01:32:35","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=2009"},"modified":"2024-02-20T19:32:35","modified_gmt":"2024-02-21T01:32:35","slug":"gp-municipio-apoya-a-los-jovenes-en-la-busqueda-de-empleo","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2024\/02\/20\/gp-municipio-apoya-a-los-jovenes-en-la-busqueda-de-empleo\/","title":{"rendered":"#GP. Municipio apoya a los j\u00f3venes en la b\u00fasqueda de empleo"},"content":{"rendered":"\n<p><strong>G\u00f3mez Palacio a 20 de febrero del 2024.<\/strong> Atendiendo las indicaciones de la presidenta municipal, Leticia Herrera Ale, de brindar a los j\u00f3venes del municipio todas las facilidades para que puedan acceder a un empleo, el Ayuntamiento dispone de una bolsa de trabajo permanente, donde se ofertan una gran variedad de opciones. Sof\u00eda Carriedo Garc\u00eda, titular del Instituto Municipal de la Juventud, dio a conocer que la bolsa de trabajo que ofrece la dependencia a su cargo, lleg\u00f3 ya a un a\u00f1o de su creaci\u00f3n, logrando durante este tiempo dar atenci\u00f3n a una gran cantidad de j\u00f3venes que han logrado encontrar empleo a trav\u00e9s del programa permanente. Manifest\u00f3 Carriedo Garc\u00eda que esta opci\u00f3n de b\u00fasqueda de trabajo que se otorga a los j\u00f3venes gomezpalatinos, se da gracias a la confianza que el gobierno que encabeza la alcaldesa Leticia Herrera Ale, genera en las empresas locales, es por ello que ofertan empleos a trav\u00e9s del Instituto. Dio a conocer que actualmente son 26 empresas, las que est\u00e1n ofertando vacantes en distintas ramas para los j\u00f3venes gomezpalatinos que deseen integrarse al \u00e1mbito laboral: Segana, Pollo Feliz, Cedis OXXO, Fermar, PC&amp;B, Mecanizados Laguna, S\u00faper Farmacia Guadalajara, Financiera Unimex, La Fortaleza, Carnicer\u00eda y Poller\u00eda \u201cLa Granja\u201d, Tuber\u00eda Laguna, San \u00c1ngel Export, Dairy Queen, Carrocer\u00edas Gallegos, Servicios Operativos Centrales, Gas Imperial, Gallegos Trailers, Cerrajer\u00eda Automotriz MG, Ingenier\u00eda en Metal Mec\u00e1nica, Financiera Lanahora, Transformadores y Subestaciones de M\u00e9xico, Taller de Costura, Tiendas Full, Plaza Imagen, Ferreter\u00eda Nueva Victoria y Proveedora Semillas de M\u00e9xico. Por ello, se invita a quienes sean mayores de edad y que actualmente buscan trabajo, a que acudan a las oficinas del Instituto Municipal de la Juventud, ubicadas en Santiago Lav\u00edn 327, zona centro, en un horario de ocho de la ma\u00f1ana a tres de la tarde. Ah\u00ed se les brindar\u00e1 toda la informaci\u00f3n necesaria para la obtenci\u00f3n de ese empleo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>G\u00f3mez Palacio a 20 de febrero del 2024. Atendiendo las indicaciones de la presidenta municipal, Leticia Herrera Ale, de brindar a los j\u00f3venes del municipio todas las facilidades para que puedan acceder a un empleo, el Ayuntamiento dispone de una bolsa de trabajo permanente, donde se ofertan una gran variedad de opciones. Sof\u00eda Carriedo Garc\u00eda, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2010,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/2009"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=2009"}],"version-history":[{"count":1,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/2009\/revisions"}],"predecessor-version":[{"id":2011,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/2009\/revisions\/2011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/2010"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=2009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=2009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=2009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}