{"id":1856,"date":"2024-02-16T14:55:24","date_gmt":"2024-02-16T20:55:24","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=1856"},"modified":"2024-02-16T14:55:24","modified_gmt":"2024-02-16T20:55:24","slug":"torreon-autoridades-mantienen-vigilancia-por-precipitacion-pluvial","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2024\/02\/16\/torreon-autoridades-mantienen-vigilancia-por-precipitacion-pluvial\/","title":{"rendered":"#Torre\u00f3n. Autoridades mantienen vigilancia por precipitaci\u00f3n pluvial"},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila. A 16 de febrero de 2024.<\/p>\n\n\n\n<p>Gracias a las acciones previas implementadas por el Plan Municipal de Atenci\u00f3n a Lluvias con acciones como mantenimiento y limpieza de c\u00e1rcamos y de pozos de captaci\u00f3n, las precipitaciones pluviales registradas en la ciudad desde ayer jueves, no han dejado afectaciones importantes ni en las principales vialidades, ni en colonias de la ciudad.<\/p>\n\n\n\n<p>El fen\u00f3meno meteorol\u00f3gico se registra de manera intermitente, y el personal de la Administraci\u00f3n Municipal mantiene rondines de vigilancia.<\/p>\n\n\n\n<p>Jorge Luis Ju\u00e1rez Llanas, director de Protecci\u00f3n Civil y Bomberos de Torre\u00f3n, inform\u00f3 que en vialidades como los bulevares Independencia, Diagonal Las Fuentes y Rodr\u00edguez Triana, no se han presentado problemas de anegaciones.<\/p>\n\n\n\n<p>Indic\u00f3 que los pozos de captaci\u00f3n ubicados en las colonias presentan niveles m\u00ednimos y actualmente cumplen su funci\u00f3n con normalidad.<\/p>\n\n\n\n<p>\u201cDesde que inici\u00f3 el a\u00f1o hemos realizado acciones del Plan Municipal de Atenci\u00f3n a Lluvias instruido por el alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez, la semana pasada trabajamos junto con otras dependencias y el SIMAS en el mantenimiento de c\u00e1rcamos y limpieza de los pozos de captaci\u00f3n, lo que ha ayudado a su correcta operaci\u00f3n\u201d.<\/p>\n\n\n\n<p>La precipitaci\u00f3n pluvial comenz\u00f3 ayer aproximadamente a las 14:00 horas y se ha mantenido de forma intermitente hasta esta ma\u00f1ana, con un acumulado de 14.1 mm.<\/p>\n\n\n\n<p>Se espera que la lluvia contin\u00fae todo el d\u00eda de hoy y el s\u00e1bado.<\/p>\n\n\n\n<p>En cuanto a los refugios temporales ubicados en las instalaciones de Protecci\u00f3n Civil y el Auditorio Municipal, el funcionario inform\u00f3 que entre la noche del jueves y la ma\u00f1ana de este viernes se atendi\u00f3 a 23 personas.<\/p>\n\n\n\n<p>Ayer por la noche personal del Sistema Integral de Mantenimiento Vial, en conjunto con elementos de la Direcci\u00f3n de Tr\u00e1nsito y Vialidad, coordinaron labores para atender los cruceros donde los sem\u00e1foros dejaron de funcionar debido a la falta de energ\u00eda el\u00e9ctrica.<\/p>\n\n\n\n<p>Por lo menos la falla se present\u00f3 en 25 dispositivos, mismos que se fueron reincorporando a la operaci\u00f3n conforme se fue restableciendo la energ\u00eda el\u00e9ctrica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 16 de febrero de 2024. Gracias a las acciones previas implementadas por el Plan Municipal de Atenci\u00f3n a Lluvias con acciones como mantenimiento y limpieza de c\u00e1rcamos y de pozos de captaci\u00f3n, las precipitaciones pluviales registradas en la ciudad desde ayer jueves, no han dejado afectaciones importantes ni en las principales vialidades, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/1856"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=1856"}],"version-history":[{"count":1,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/1856\/revisions"}],"predecessor-version":[{"id":1858,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/1856\/revisions\/1858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/1857"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=1856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=1856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=1856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}