{"id":13146,"date":"2024-11-29T15:02:10","date_gmt":"2024-11-29T21:02:10","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=13146"},"modified":"2024-11-29T15:02:11","modified_gmt":"2024-11-29T21:02:11","slug":"lerdo-es-san-jacinto-comunidad-certificada-en-salud-por-ssd","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2024\/11\/29\/lerdo-es-san-jacinto-comunidad-certificada-en-salud-por-ssd\/","title":{"rendered":"#Lerdo. ES SAN JACINTO COMUNIDAD CERTIFICADA EN SALUD POR SSD*"},"content":{"rendered":"\n<ul>\n<li>En este a\u00f1o se certificaron las comunidades de Graseros y San Jacinto en el municipio de Lerdo.<\/li>\n<\/ul>\n\n\n\n<p>Lerdo, 29 de noviembre 2024.- El pasado jueves, en la comunidad de San Jacinto se desarroll\u00f3 el Evento de \u201cCertificaci\u00f3n de Comunidad como Promotora de la Salud\u201d, a trav\u00e9s de la Secretar\u00eda de Salud del Estado de Durango y con la participaci\u00f3n del Salud Municipal y Prevenci\u00f3n Social de Lerdo.<\/p>\n\n\n\n<p>Se cont\u00f3 con la presencia de la Diputada Local Susy Torrecillas Salazar; en representaci\u00f3n del Presidente Municipal Homero Mart\u00ednez Cabrera, el Secretario T\u00e9cnico Ramon Acosta; la Dra. del Centro de Salud de San Jacinto, Laura Godoy; el Dr. Cecilio Medina de Salud Municipal; Roberto Carlos Calder\u00f3n, titular del departamento de Prevenci\u00f3n Social; adem\u00e1s de autoridades estatales.<\/p>\n\n\n\n<p>El Secretario T\u00e9cnico Ram\u00f3n Acosta, destac\u00f3 que el Presidente Municipal Homero Mart\u00ednez Cabrera celebra la participaci\u00f3n del comit\u00e9 de salud, conformado en la comunidad, que ha puesto en marcha acciones en beneficio de los habitantes.<\/p>\n\n\n\n<p>As\u00ed mismo, el centro de salud de la comunidad ha fortalecido las actividades de concientizaci\u00f3n y prevenci\u00f3n en el tema de vacunaciones a ni\u00f1os para completar esquemas, vacunaciones antirr\u00e1bicas para las mascotas, pl\u00e1ticas e informaci\u00f3n para prevenir el c\u00e1ncer de mama y cervicouterino, diabetes e hipertensi\u00f3n, entre otras.<\/p>\n\n\n\n<p>Adem\u00e1s de garantizar que los espacios p\u00fablicos en San Jacinto se encuentren en buen estado, atendiendo el tema de salubridad.<\/p>\n\n\n\n<p>Se explic\u00f3 que una Certificaci\u00f3n de Comunidad Saludable se brinda a los poblados que cumplen con los est\u00e1ndares b\u00e1sicos de salud, por lo que la Secretar\u00eda de Salud a nivel Estatal alz\u00f3, simb\u00f3licamente, una bandera blanca para indicar que San Jacinto est\u00e1 certificado en este \u00e1mbito.<\/p>\n\n\n\n<p>Cabe se\u00f1alar que, durante el evento, se brindaron consultas gratuitas y vacunaciones tanto para la ciudadan\u00eda, como para las mascotas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lerdo, 29 de noviembre 2024.- El pasado jueves, en la comunidad de San Jacinto se desarroll\u00f3 el Evento de \u201cCertificaci\u00f3n de Comunidad como Promotora de la Salud\u201d, a trav\u00e9s de la Secretar\u00eda de Salud del Estado de Durango y con la participaci\u00f3n del Salud Municipal y Prevenci\u00f3n Social de Lerdo. Se cont\u00f3 con la presencia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13146"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=13146"}],"version-history":[{"count":1,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13146\/revisions"}],"predecessor-version":[{"id":13148,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13146\/revisions\/13148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/13147"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=13146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=13146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=13146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}