{"id":13103,"date":"2024-11-28T18:09:59","date_gmt":"2024-11-29T00:09:59","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=13103"},"modified":"2024-11-28T18:10:00","modified_gmt":"2024-11-29T00:10:00","slug":"torreon-turismo-municipal-promueve-la-identidad-de-torreon-entre-estudiantes-universitarios","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2024\/11\/28\/torreon-turismo-municipal-promueve-la-identidad-de-torreon-entre-estudiantes-universitarios\/","title":{"rendered":"#Torre\u00f3n. Turismo Municipal promueve la identidad de Torre\u00f3n entre estudiantes universitarios"},"content":{"rendered":"\n<p>Torre\u00f3n, Coahuila a 28 de noviembre de 2024<\/p>\n\n\n\n<p>La Direcci\u00f3n de Turismo Municipal particip\u00f3 en la presentaci\u00f3n de un proyecto de diagn\u00f3stico de comunicaci\u00f3n y promoci\u00f3n de las pr\u00e1cticas profesionales, realizado por alumnos de la Universidad Iberoamericana.<\/p>\n\n\n\n<p>Luis T\u00e9llez Montes, director de la dependencia, mencion\u00f3 que personal de la direcci\u00f3n a su cargo atendi\u00f3 la invitaci\u00f3n de la universidad.<\/p>\n\n\n\n<p>\u201cSe les explic\u00f3 a los alumnos la importancia de preservar y fomentar la identidad torreonense a trav\u00e9s de la marca \u201cYo amo Torre\u00f3n\u201d, y \u201cYo amo el Pan Franc\u00e9s\u201d que fue impulsada desde la direcci\u00f3n, por la Administraci\u00f3n Municipal del alcalde Rom\u00e1n Alberto Cepeda Gonz\u00e1lez\u201d, coment\u00f3 el director.<\/p>\n\n\n\n<p>Lo anterior, dijo, debido a la trascendencia de la conmemoraci\u00f3n del D\u00eda del Pan Franc\u00e9s, ya que fue un logro que se obtuvo por encima de una tierra panadera por excelencia, como Par\u00eds.<\/p>\n\n\n\n<p>Cabe mencionar que la elecci\u00f3n del 16 de octubre para conmemorar el D\u00eda del Pan Franc\u00e9s en Torre\u00f3n es reciente, y se debe a su coincidencia con el D\u00eda Internacional del Pan.<\/p>\n\n\n\n<p>Durante la presentaci\u00f3n, tambi\u00e9n se dieron a conocer las bondades de las nuevas opciones tur\u00edsticas que hay en Torre\u00f3n, ya que por las caracter\u00edsticas de la regi\u00f3n ya se cuenta con el turismo de negocios, m\u00e9dico y de otros tipos.<\/p>\n\n\n\n<p>Adem\u00e1s, se dio a conocer a los universitarios el programa de vinculaci\u00f3n estudiantil, el cual invita a los alumnos a realizar sus pr\u00e1cticas profesionales y su servicio social en la Direcci\u00f3n de Turismo Municipal.<\/p>\n\n\n\n<p>\u201cEste a\u00f1o ya finaliz\u00f3 el programa, debido al proceso de entrega- recepci\u00f3n, pero se contempla que el pr\u00f3ximo a\u00f1o se reanude a inicios del mes de enero\u201d, destac\u00f3 el funcionario.<\/p>\n\n\n\n<p>Dijo que en el programa se solicitar\u00e1n practicantes de dise\u00f1o gr\u00e1fico y comunicaci\u00f3n, que sepan de fotograf\u00eda y que tengan facilidad para el manejo de las redes sociales, sumado a el trabajo que ya se realiza con estudiantes de las licenciaturas en turismo y gastronom\u00eda, con quienes tienen estrecha colaboraci\u00f3n.<\/p>\n\n\n\n<p>Guadalupe Molina S\u00e1nchez, auxiliar de comunicaci\u00f3n de la direcci\u00f3n, se encarg\u00f3 de exponer ante los estudiantes las acciones del Municipio para la promoci\u00f3n de Torre\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila a 28 de noviembre de 2024 La Direcci\u00f3n de Turismo Municipal particip\u00f3 en la presentaci\u00f3n de un proyecto de diagn\u00f3stico de comunicaci\u00f3n y promoci\u00f3n de las pr\u00e1cticas profesionales, realizado por alumnos de la Universidad Iberoamericana. Luis T\u00e9llez Montes, director de la dependencia, mencion\u00f3 que personal de la direcci\u00f3n a su cargo atendi\u00f3 la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13103"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=13103"}],"version-history":[{"count":1,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13103\/revisions"}],"predecessor-version":[{"id":13105,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13103\/revisions\/13105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/13104"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=13103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=13103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=13103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}