{"id":13085,"date":"2024-11-28T16:28:04","date_gmt":"2024-11-28T22:28:04","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=13085"},"modified":"2024-11-28T16:28:04","modified_gmt":"2024-11-28T22:28:04","slug":"lerdo-impulsara-lerdo-el-sistema-de-monitoreo-municipal-simon-a-traves-de-seguridad-publica","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2024\/11\/28\/lerdo-impulsara-lerdo-el-sistema-de-monitoreo-municipal-simon-a-traves-de-seguridad-publica\/","title":{"rendered":"#Lerdo. IMPULSAR\u00c1 LERDO EL SISTEMA DE MONITOREO MUNICIPAL (SIMON) A TRAV\u00c9S DE SEGURIDAD P\u00daBLICA*"},"content":{"rendered":"\n<ul>\n<li>En una primera etapa se establecer\u00e1 la videovigilancia de edificios de gobierno y equipo del SAPAL<\/li>\n<\/ul>\n\n\n\n<p>Lerdo, 28 de noviembre 2024.- Este jueves, durante la sesi\u00f3n de Cabildo Ordinaria n\u00famero 103, se aprob\u00f3 por unanimidad una reforma al reglamento interior de la Polic\u00eda Preventiva Municipal de Ciudad Lerdo. Esta modificaci\u00f3n permitir\u00e1 implementar el Sistema de Monitoreo Municipal (SIMON) para la vigilancia de espacios p\u00fablicos, iniciando con oficinas de gobierno y el equipamiento del SAPAL en su primera etapa.<\/p>\n\n\n\n<p>En rueda de prensa posterior a la sesi\u00f3n, el Alcalde agradeci\u00f3 a los regidores por su apoyo a esta reforma, destacando su impacto en la vigilancia de los espacios p\u00fablicos.<\/p>\n\n\n\n<p>\u201cEstamos haciendo una remodelaci\u00f3n al edificio donde a trav\u00e9s de esta reforma, vamos a incluir cinco \u00e1reas fundamentales, como un \u00e1rea de atenci\u00f3n psicol\u00f3gica para priorizar la salud mental de nuestros elementos, los cuales diariamente atienden una llamada de emergencia y visualizan temas de suma importancia; y el Sistema de Monitoreo Municipal (SIMON). Este permitir\u00e1 que todas las c\u00e1maras est\u00e9n enlazadas y podamos atender cualquier irregularidad en tiempo real\u201d, se\u00f1al\u00f3 el edil.<\/p>\n\n\n\n<p>El Alcalde enfatiz\u00f3 que esta medida responde al incremento de vandalismo en equipos del SAPAL, como c\u00e1rcamos de drenaje y pozos de agua potable. Estos equipos ser\u00e1n equipados con c\u00e1maras de seguridad monitoreadas 24\/7, para garantizar su protecci\u00f3n.<\/p>\n\n\n\n<p>Adem\u00e1s, mencion\u00f3 que en una segunda etapa se ofrecer\u00e1 el servicio de monitoreo a empresas locales, integrando sus c\u00e1maras al SIMON. Esto permitir\u00e1 atender emergencias, robos o actos de vandalismo en menos de cinco minutos.<\/p>\n\n\n\n<p>Se prev\u00e9 la instalaci\u00f3n de m\u00e1s de 50 c\u00e1maras de vigilancia enlazadas a la Direcci\u00f3n de Seguridad P\u00fablica y una colaboraci\u00f3n permanente con el C4.<\/p>\n\n\n\n<p>\u201cEl objetivo es consolidar un sistema de monitoreo propio. Planeamos etiquetar recursos para incluir las entradas principales al SIMON, fortaleciendo nuestra capacidad de vigilancia y modernizaci\u00f3n. Este es un gran paso para Ciudad Lerdo frente al avance de otras ciudades como Torre\u00f3n\u201d, concluy\u00f3 el Alcalde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lerdo, 28 de noviembre 2024.- Este jueves, durante la sesi\u00f3n de Cabildo Ordinaria n\u00famero 103, se aprob\u00f3 por unanimidad una reforma al reglamento interior de la Polic\u00eda Preventiva Municipal de Ciudad Lerdo. Esta modificaci\u00f3n permitir\u00e1 implementar el Sistema de Monitoreo Municipal (SIMON) para la vigilancia de espacios p\u00fablicos, iniciando con oficinas de gobierno y el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13086,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13085"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=13085"}],"version-history":[{"count":1,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13085\/revisions"}],"predecessor-version":[{"id":13087,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13085\/revisions\/13087"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/13086"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=13085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=13085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=13085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}