{"id":13048,"date":"2024-11-27T14:29:17","date_gmt":"2024-11-27T20:29:17","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=13048"},"modified":"2024-11-27T14:29:17","modified_gmt":"2024-11-27T20:29:17","slug":"gp-sideapa-y-salud-municipal-trabajan-en-conjunto-para-atender-brote-de-mosquitos-en-urbivillas","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2024\/11\/27\/gp-sideapa-y-salud-municipal-trabajan-en-conjunto-para-atender-brote-de-mosquitos-en-urbivillas\/","title":{"rendered":"#GP. Sideapa y Salud Municipal trabajan en conjunto para atender brote de mosquitos en Urbivillas.*"},"content":{"rendered":"\n<ul>\n<li>Salud municipal aclara que no hay riesgo de dengue<\/li>\n<\/ul>\n\n\n\n<p>El Ayuntamiento de G\u00f3mez Palacio, a trav\u00e9s del Sistema Descentralizado de Agua Potable y Alcantarillado y la direcci\u00f3n de Salud Municipal se encuentran trabajando desde el pasado lunes 25 de noviembre para atender un brote de mosquitos en el fraccionamiento Urbivillas.<\/p>\n\n\n\n<p>Francisco Escalera Tostado director del Sideapa indic\u00f3 que este brote de mosquitos se origin\u00f3 por la acumulaci\u00f3n de aguas negras en un sector de la colonia, lo que ocurre de manera recurrente por la falta de cultura de los vecinos que depositan constantemente desechos en el drenaje sanitario lo que impide el adecuado flujo de las aguas residuales.<\/p>\n\n\n\n<p>Escalera Tostado indic\u00f3 que, a pesar de que se trata de un fraccionamiento irregular que no ha sido entregado al Ayuntamiento, tienen la instrucci\u00f3n de la Presidenta Municipal Leticia Herrera Ale, de atender este tipo de reportes realizados por la ciudadan\u00eda.<\/p>\n\n\n\n<p>Por su parte, Jos\u00e9 Antonio Adema de Le\u00f3n, titular de Salud Municipal, explic\u00f3 que la poblaci\u00f3n no debe alarmarse por la propagaci\u00f3n del dengue, ya que el mosquito Aedes Aegypti, no se reproduce en aguas residuales, sino solamente en agua limpia, por lo cual, aunque sea molesto no representa un riesgo de salud.<\/p>\n\n\n\n<p>\u201cEl mosquito que estamos combatiendo en Urbivillas corresponde a la especie Culex, es m\u00e1s obscuro y m\u00e1s grande que el Aedes Aegypti, pero es inofensivo, pues no es transmisor de ninguna enfermedad, solamente es molesto.\u201d indic\u00f3 el director de Salud Municipal<\/p>\n\n\n\n<p>Adame de Le\u00f3n indic\u00f3 que, de manera paralela a las acciones de Sideapa para retirar las aguas negras, la direcci\u00f3n a su cargo ya inici\u00f3 con las labores de fumigaci\u00f3n para terminar con este brote de moscos, el cual corresponde a la especie.<\/p>\n\n\n\n<p>\u201cEstimamos que tanto los trabajos del retiro de aguas residuales como la fumigaci\u00f3n del \u00e1rea, quede culminada el d\u00eda de hoy\u201d, dijo el funcionario.<\/p>\n\n\n\n<p>Sin embargo, seguimos exhortando a la poblaci\u00f3n para que evite saturar las alcantarillas, pues es recurrente esta situaci\u00f3n y los \u00fanicos afectados son los propios vecinos del lugar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de G\u00f3mez Palacio, a trav\u00e9s del Sistema Descentralizado de Agua Potable y Alcantarillado y la direcci\u00f3n de Salud Municipal se encuentran trabajando desde el pasado lunes 25 de noviembre para atender un brote de mosquitos en el fraccionamiento Urbivillas. Francisco Escalera Tostado director del Sideapa indic\u00f3 que este brote de mosquitos se origin\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13048"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=13048"}],"version-history":[{"count":1,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13048\/revisions"}],"predecessor-version":[{"id":13050,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13048\/revisions\/13050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/13049"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=13048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=13048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=13048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}