{"id":13042,"date":"2024-11-27T14:24:54","date_gmt":"2024-11-27T20:24:54","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=13042"},"modified":"2024-11-27T14:24:54","modified_gmt":"2024-11-27T20:24:54","slug":"gp-ayuntamiento-a-traves-del-sideapa-regala-abate-a-los-gomezpalatinos","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2024\/11\/27\/gp-ayuntamiento-a-traves-del-sideapa-regala-abate-a-los-gomezpalatinos\/","title":{"rendered":"#GP. Ayuntamiento a trav\u00e9s del Sideapa regala abate a los gomezpalatinos*"},"content":{"rendered":"\n<p>Continuando con las acciones preventivas para combatir el dengue, el Ayuntamiento de G\u00f3mez Palacio, a trav\u00e9s del Sistema Descentralizado de Agua Potable y Alcantarillado (Sideapa), reafirma su compromiso con la salud p\u00fablica mediante una campa\u00f1a de distribuci\u00f3n gratuita de abate, buscando con ello la erradicaci\u00f3n del mosquito Aedes aegypti, transmisor de esta enfermedad.<\/p>\n\n\n\n<p>Francisco Escalera Tostado, director del Sideapa, destac\u00f3 que esta iniciativa se lleva a cabo por instrucciones de la Presidenta Municipal, Leticia Herrera Ale, para reducir la proliferaci\u00f3n del mosquito. \u201cInvitamos a todos los gomezpalatinos a aprovechar este servicio gratuito y a unirse a las acciones de prevenci\u00f3n contra el dengue\u201d, afirm\u00f3 Escalera Tostado.<\/p>\n\n\n\n<p>\u201cEl abate es crucial para eliminar las larvas del mosquito en los criaderos y as\u00ed romper el ciclo de transmisi\u00f3n de la enfermedad\u201d, explic\u00f3 el titular del Sideapa.<\/p>\n\n\n\n<p>Los ciudadanos pueden obtener el abate sin costo en las oficinas centrales del Sideapa, situadas en Avenida Victoria 544 Norte, Zona Centro. El horario de atenci\u00f3n es de lunes a viernes, de 8:00 a.m. a 3:30 p.m., y los s\u00e1bados de 8:00 a.m. a 1:00 p.m.<\/p>\n\n\n\n<p>Adem\u00e1s de solicitar el abate, el Sideapa exhorta a la poblaci\u00f3n a adoptar medidas preventivas como eliminar criaderos, revisar y deshacerse de objetos que acumulen agua, cubrir dep\u00f3sitos de agua con mallas finas para impedir la reproducci\u00f3n de mosquitos, limpiar canales y desag\u00fces y utilizar repelente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuando con las acciones preventivas para combatir el dengue, el Ayuntamiento de G\u00f3mez Palacio, a trav\u00e9s del Sistema Descentralizado de Agua Potable y Alcantarillado (Sideapa), reafirma su compromiso con la salud p\u00fablica mediante una campa\u00f1a de distribuci\u00f3n gratuita de abate, buscando con ello la erradicaci\u00f3n del mosquito Aedes aegypti, transmisor de esta enfermedad. Francisco Escalera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13042"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=13042"}],"version-history":[{"count":1,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13042\/revisions"}],"predecessor-version":[{"id":13044,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/13042\/revisions\/13044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/13043"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=13042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=13042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=13042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}