{"id":12055,"date":"2024-11-06T14:54:59","date_gmt":"2024-11-06T20:54:59","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=12055"},"modified":"2024-11-06T14:54:59","modified_gmt":"2024-11-06T20:54:59","slug":"durango-juntos-llevaremos-alegria-a-los-ninos-de-durango-presenta-marisol-kermesse-de-la-familia-villista-el-radiomaraton-y-el-jugueton-2024","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2024\/11\/06\/durango-juntos-llevaremos-alegria-a-los-ninos-de-durango-presenta-marisol-kermesse-de-la-familia-villista-el-radiomaraton-y-el-jugueton-2024\/","title":{"rendered":"#Durango. Juntos llevaremos alegr\u00eda a los ni\u00f1os de Durango; presenta Marisol Kermesse de la Familia Villista, el Radiomarat\u00f3n y el Juguet\u00f3n 2024*"},"content":{"rendered":"\n<ul>\n<li><em>Las actividades iniciar\u00e1n el 17 de noviembre en la FENADU donde regresar\u00e1 la tradicional t\u00f3mbola y culminar\u00e1n el 23 de este mes en la plaza IV Centenario.<\/em><\/li>\n\n\n\n<li><em>En la velaria se presentar\u00e1n Los Huracanes del Norte, cuya agrupaci\u00f3n amenizar\u00e1 con su m\u00fasica norte\u00f1a esta gran fiesta.<\/em><\/li>\n\n\n\n<li><em>La meta para este a\u00f1o es reunir 11 millones de pesos y recolectar m\u00e1s de 233 mil juguetes.<\/em><\/li>\n<\/ul>\n\n\n\n<p>\u00a1Lleg\u00f3 el momento de unirnos para llevar alegr\u00eda a los ni\u00f1os de Durango en esta Navidad! extern\u00f3 Marisol Rosso Rivera, presidenta de DIF Estatal al presentar la Kermesse de la Familia Villista, el Radiomarat\u00f3n y el Juguet\u00f3n 2024, eventos que permitir\u00e1n regalar juguetes a los m\u00e1s peque\u00f1os del hogar en todo el estado.<\/p>\n\n\n\n<p>\u201cNos espera una gran aventura y muchos retos que cumplir, porque lo que de verdad interesa es la sonrisa y felicidad de nuestros ni\u00f1os\u201d, la presidenta del organismo asistencial al detallar que la Kermesse de la Familia Villista 2024 se llevar\u00e1 a cabo el pr\u00f3ximo domingo 17 de noviembre, en las instalaciones de la FENADU con transporte gratuito.<\/p>\n\n\n\n<p>Este mismo d\u00eda, se podr\u00e1 disfrutar de la Feria de Escaramuzas en el lienzo charro, de deliciosa comida en el \u00e1rea gastron\u00f3mica con m\u00e1s de 55 puestos, lo mismo de exhibici\u00f3n de autos cl\u00e1sicos; la Ruta de la Salud gratuita, t\u00f3mbola, una funci\u00f3n de lucha libre y para cerrar, el concierto de Los Huracanes del Norte que presentar\u00e1n su tour &#8220;Todo Contigo&#8221;.<\/p>\n\n\n\n<p>Asimismo, Rosso Rivera mencion\u00f3 que las actividades para recabar juguetes para llevarlos a los ni\u00f1os ser\u00e1n el pr\u00f3ximo viernes 22 de noviembre en la Laguna, en el Parque La Esperanza a partir de las 8 horas, esto con el Juguet\u00f3n; y el s\u00e1bado 23 en el Radiomarat\u00f3n que se llevar\u00e1 a cabo en la plaza IV Centenario.<\/p>\n\n\n\n<p>La organizaci\u00f3n estar\u00e1 a cargo de la Benem\u00e9rita y Centenaria Escuela Normal del Estado de Durango (ByCENED) y se tendr\u00e1n actividades como la carrera de botargas como un evento que llama la atenci\u00f3n para la diversi\u00f3n de los asistentes; y al igual que el a\u00f1o pasado, habr\u00e1 personas encargadas de recibir los juguetes en los veh\u00edculos para evitar problemas de estacionamiento y aglomeraciones.<\/p>\n\n\n\n<p>El director de la ByCENED, Jes\u00fas Roberto Robles Zapata, record\u00f3 que esta actividad que tuvo inicio hace 25 a\u00f1os, con uni\u00f3n de voluntades, mentes, almas y corazones, tiene la finalidad de reunir juguetes para arrancar sonrisas, por ello, ahora que su instituci\u00f3n es la encargada de la organizaci\u00f3n, asegur\u00f3 que intentar\u00e1n dar un impulso fuerte a la participaci\u00f3n de todos, para lograr recaudar los resultados en la meta trazada.<\/p>\n\n\n\n<p>Los boletos para el concierto de Los Huracanes del Norte est\u00e1n disponibles en la p\u00e1gina de Ticketstar, Agencia Signature, El Vaquero Norte\u00f1o, en las sucursales de Paseo Durango y avenida 20 de Noviembre, con precios de entre 150 a los 800 pesos, indic\u00f3 Lauro Arce Gallegos, director de Ferias, Espect\u00e1culos y Paseos Tur\u00edsticos<\/p>\n\n\n\n<p>La meta para este a\u00f1o es reunir 11 millones de pesos y recolectar m\u00e1s de 233 mil juguetes, agreg\u00f3 Marisol Rosso al invitar a todos los duranguenses a unirse a esta causa y llevar alegr\u00eda a los ni\u00f1os de Durango.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Lleg\u00f3 el momento de unirnos para llevar alegr\u00eda a los ni\u00f1os de Durango en esta Navidad! extern\u00f3 Marisol Rosso Rivera, presidenta de DIF Estatal al presentar la Kermesse de la Familia Villista, el Radiomarat\u00f3n y el Juguet\u00f3n 2024, eventos que permitir\u00e1n regalar juguetes a los m\u00e1s peque\u00f1os del hogar en todo el estado. \u201cNos espera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12056,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/12055"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=12055"}],"version-history":[{"count":1,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/12055\/revisions"}],"predecessor-version":[{"id":12057,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/12055\/revisions\/12057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/12056"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=12055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=12055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=12055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}