{"id":11969,"date":"2024-11-04T16:12:28","date_gmt":"2024-11-04T22:12:28","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=11969"},"modified":"2024-11-04T16:13:45","modified_gmt":"2024-11-04T22:13:45","slug":"durango-gobernador-esteban-villegas-villarreal-y-la-alcaldesa-leticia-herrera-ale-inician-entrega-de-cuartos-adicionales-a-20-familias","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2024\/11\/04\/durango-gobernador-esteban-villegas-villarreal-y-la-alcaldesa-leticia-herrera-ale-inician-entrega-de-cuartos-adicionales-a-20-familias\/","title":{"rendered":"#GP. Gobernador Esteban Villegas Villarreal y la Alcaldesa Leticia Herrera Ale inician entrega de cuartos adicionales a 20 familias*"},"content":{"rendered":"\n<p>La Presidenta Municipal Leticia Herrera Ale, acompa\u00f1\u00f3 al Gobernador del Estado, Esteban Villegas Villarreal a la entrega simb\u00f3lica de un cuarto adicional en la colonia Tierra y Libertad, de un total de 20 cuartos que se entregar\u00e1n en el municipio, con los cuales se ver\u00e1n beneficiadas igual n\u00famero de familias gomezpalatinas que viv\u00edan en condiciones de hacinamiento.<\/p>\n\n\n\n<p>Este programa es una muestra del compromiso del Gobernador de Durango con el bienestar social y el desarrollo comunitario. La iniciativa mejora sustancialmente las condiciones de vida de estas familias, fortalece la cohesi\u00f3n social y apoya el crecimiento integral de la comunidad beneficiada.<\/p>\n\n\n\n<p>La Presidenta Municipal Leticia Herrera Ale, se\u00f1al\u00f3 que estos cuartos entregados a familias gomezpalatinas, son una muestra del compromiso que el Gobernador del Estado Esteban Villegas Villarreal, tiene con el bienestar de las familias m\u00e1s vulnerables, que con esta acci\u00f3n, mejorar\u00e1n sus condiciones de vida.<\/p>\n\n\n\n<p>Los cuartos dormitorios entregados, cuentan con una superficie de 4.50 m x 3.70 m, con cuatro muros de block de concreto, cimentaci\u00f3n de mamposter\u00eda y losa de 10 cm de espesor, lo que garantiza la durabilidad de la construcci\u00f3n.<\/p>\n\n\n\n<p>Los cuartos se realizaron con recursos del Fondo de Infraestructura para el Desarrollo Social (FAIS) del Ramo 33.<\/p>\n\n\n\n<p>De esta manera, el Gobierno Municipal y el Gobierno del Estado, mejoran significativamente la calidad de vida de los gomezpalatinos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Presidenta Municipal Leticia Herrera Ale, acompa\u00f1\u00f3 al Gobernador del Estado, Esteban Villegas Villarreal a la entrega simb\u00f3lica de un cuarto adicional en la colonia Tierra y Libertad, de un total de 20 cuartos que se entregar\u00e1n en el municipio, con los cuales se ver\u00e1n beneficiadas igual n\u00famero de familias gomezpalatinas que viv\u00edan en condiciones [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/11969"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=11969"}],"version-history":[{"count":2,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/11969\/revisions"}],"predecessor-version":[{"id":11972,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/11969\/revisions\/11972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/11970"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=11969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=11969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=11969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}