{"id":11910,"date":"2024-11-02T13:19:42","date_gmt":"2024-11-02T19:19:42","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=11910"},"modified":"2024-11-02T13:19:42","modified_gmt":"2024-11-02T19:19:42","slug":"torreon-acuden-mas-de-30-mil-personas-a-panteones-de-torreon-esperan-mas-visitas-para-esta-tarde","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2024\/11\/02\/torreon-acuden-mas-de-30-mil-personas-a-panteones-de-torreon-esperan-mas-visitas-para-esta-tarde\/","title":{"rendered":"#Torre\u00f3n. Acuden m\u00e1s de 30 mil personas a panteones de Torre\u00f3n, esperan m\u00e1s visitas para esta tarde"},"content":{"rendered":"\n<p><strong>Torre\u00f3n, Coahuila. A 2 de noviembre de 2024.- E<\/strong>ntre el viernes 1 de noviembre y la ma\u00f1ana de este s\u00e1bado, ya suman 30 mil personas que han visitado los diferentes panteones de Torre\u00f3n, prevaleciendo el orden por parte de la ciudadan\u00eda que ha seguido las indicaciones de las autoridades. Jorge Luis Ju\u00e1rez Llanas, director de Protecci\u00f3n Civil y Bomberos de Torre\u00f3n, dijo que la actividad durante las primeras horas de este s\u00e1bado inici\u00f3 con regularidad sin que hasta este momento se haya reportado alg\u00fan incidente. El director destac\u00f3 el buen comportamiento de los ciudadanos que han acudido a los diferentes camposantos, quienes se han conducido con orden y atendiendo las indicaciones de las autoridades y del personal de los panteones. \u201cLos operativos iniciaron el d\u00eda de ayer en panteones como el Municipal 1 y 2, Jardines del Carmen, Jardines del Tiempo, as\u00ed como en los ejidales: San Antonio de los Bravos, El \u00c1guila y La Uni\u00f3n, entre otros, y el ayer al cierre se contabilizaron 10 mil personas\u201d, indic\u00f3. Agreg\u00f3 que durante la ma\u00f1ana de este s\u00e1bado se ha registrado el acceso de 20 mil visitantes m\u00e1s en los camposantos. El funcionario mencion\u00f3 que el operativo conjunto continuar\u00e1 el d\u00eda de hoy posterior al cierre de los panteones que es a las 18:00 horas. \u201cContinuar\u00e1 la presencia despu\u00e9s del cierre en lo que respecta al apoyo en el desfogue de tr\u00e1fico, seguridad y las acciones de limpieza\u201d, coment\u00f3 el director. Ju\u00e1rez Llanas dijo que se espera un aumento de visitas a\u00fan para esta tarde y que se extienda al d\u00eda de ma\u00f1ana para quienes por sus actividades laborales no pudieron acudir el 1 y 2 de noviembre. Destac\u00f3 que aunque el operativo inici\u00f3 ayer, la labor de la Administraci\u00f3n Municipal fue con anticipaci\u00f3n con acciones de limpieza y se\u00f1alizaci\u00f3n de \u00e1reas de riesgo. Participan tambi\u00e9n dependencias como Seguridad P\u00fablica, Tr\u00e1nsito y Vialidad, Inspecci\u00f3n y Verificaci\u00f3n, Plazas y Mercados, Servicios P\u00fablicos y La Ola, Salud Municipal y la Jurisdicci\u00f3n Sanitaria VI y el apoyo de la Cruz Roja.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torre\u00f3n, Coahuila. A 2 de noviembre de 2024.- Entre el viernes 1 de noviembre y la ma\u00f1ana de este s\u00e1bado, ya suman 30 mil personas que han visitado los diferentes panteones de Torre\u00f3n, prevaleciendo el orden por parte de la ciudadan\u00eda que ha seguido las indicaciones de las autoridades. Jorge Luis Ju\u00e1rez Llanas, director de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/11910"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=11910"}],"version-history":[{"count":1,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/11910\/revisions"}],"predecessor-version":[{"id":11912,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/11910\/revisions\/11912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/11911"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=11910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=11910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=11910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}