{"id":11866,"date":"2024-11-01T17:42:16","date_gmt":"2024-11-01T23:42:16","guid":{"rendered":"https:\/\/zonalimitrofe-cbnr.com\/?p=11866"},"modified":"2024-11-01T17:43:29","modified_gmt":"2024-11-01T23:43:29","slug":"congresocoahuila-fortalecer-uso-de-herramientas-y-procesos-digitales-en-micro-pequenas-y-medianas-empresas-solicita-beatriz-fraustro","status":"publish","type":"post","link":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/2024\/11\/01\/congresocoahuila-fortalecer-uso-de-herramientas-y-procesos-digitales-en-micro-pequenas-y-medianas-empresas-solicita-beatriz-fraustro\/","title":{"rendered":"#CongresoCoahuila. Fortalecer uso de herramientas y procesos digitales en micro, peque\u00f1as y medianas empresas, solicita Beatriz Fraustro"},"content":{"rendered":"\n<p><strong>Saltillo, Coahuila, 01 de noviembre de 2024.- <\/strong>En sesi\u00f3n del Congreso del Estado se aprob\u00f3 el punto de acuerdo presentado por la diputada Beatriz Eugenia Fraustro D\u00e1vila, mediante el cual exhorta a la Secretar\u00eda de Econom\u00eda del gobierno federal, que a trav\u00e9s de sus oficinas de representaci\u00f3n y en colaboraci\u00f3n con sus hom\u00f3logas en los estados, ampl\u00ede en el pa\u00eds el Programa de Educaci\u00f3n Digital con el objetivo de ofrecer a un mayor n\u00famero de micro, peque\u00f1as y medianas empresas (MIPYMES) talleres presenciales que fortalezcan sus habilidades en el uso de herramientas y procesos digitales. El uso de las redes sociales, el comercio digital, los servicios en la nube, entre otras herramientas, han permeado r\u00e1pidamente en la sociedad; y aunque la consecuencia natural debi\u00f3 haber sido que las micro, peque\u00f1as y medianas empresas hubieran asumido de inmediato esta transformaci\u00f3n, en algunos casos eso no pas\u00f3. Seg\u00fan un reporte del Instituto Federal de Telecomunicaciones, para 2023 el 76% de las MIPYMES no estaban insertas en la econom\u00eda digital. Esta desconexi\u00f3n con la tecnolog\u00eda afecta de forma m\u00e1s importante a las microempresas. Por otro lado, la Secretar\u00eda de Econom\u00eda plante\u00f3 impulsar en este sector medidas de inclusi\u00f3n digital que les permitieran incrementar sus ventas, aumentar su competitividad y garantizar una mayor esperanza de vida a sus establecimientos. Incorporarse a este ecosistema digital va m\u00e1s all\u00e1 de utilizar redes sociales o de tener una p\u00e1gina de internet; se trata de redefinir c\u00f3mo operan las empresas, se relacionan con los clientes y crean valor. La diputada reconoci\u00f3 las acciones emprendidas por la dependencia federal para mejorar las habilidades digitales de las micro, peque\u00f1as y medianas empresas, asimismo resalt\u00f3 los programas y acciones implementados por el gobernador Manolo Jim\u00e9nez Salinas, para elevar la competitividad de los negocios. \u201cTrabajando juntos podemos redoblar estos esfuerzos y fortalecer la cadena de valor. En ese sentido hacemos un atento llamado a la Secretar\u00eda de Econom\u00eda federal a fin de aprovechar al m\u00e1ximo la enorme oportunidad que representa para las MIPYMES el proceso de transformaci\u00f3n digital, haciendo llegar sus programas y cualquier otro que se derive de la Alianza por la Transformaci\u00f3n Digital, de forma presencial a los diferentes puntos del pa\u00eds\u201d explic\u00f3 Beatriz Fraustro en el punto de acuerdo aprobado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila, 01 de noviembre de 2024.- En sesi\u00f3n del Congreso del Estado se aprob\u00f3 el punto de acuerdo presentado por la diputada Beatriz Eugenia Fraustro D\u00e1vila, mediante el cual exhorta a la Secretar\u00eda de Econom\u00eda del gobierno federal, que a trav\u00e9s de sus oficinas de representaci\u00f3n y en colaboraci\u00f3n con sus hom\u00f3logas en los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11869,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/11866"}],"collection":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/comments?post=11866"}],"version-history":[{"count":1,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/11866\/revisions"}],"predecessor-version":[{"id":11868,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/posts\/11866\/revisions\/11868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media\/11869"}],"wp:attachment":[{"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/media?parent=11866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/categories?post=11866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zonalimitrofe-cbnr.com\/index.php\/wp-json\/wp\/v2\/tags?post=11866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}